{"id":950,"date":"2015-06-04T13:50:03","date_gmt":"2015-06-04T12:50:03","guid":{"rendered":"http:\/\/www.geschiebekunde.de\/?p=950"},"modified":"2021-02-06T20:33:04","modified_gmt":"2021-02-06T19:33:04","slug":"geschiebe-des-jahres-2015","status":"publish","type":"post","link":"https:\/\/www.geschiebekunde.de\/nl\/geschiebe-des-jahres-2015\/","title":{"rendered":"Gidsgesteenten voor het jaar 2015"},"content":{"rendered":"<figure style=\"width: 225px\" class=\"wp-caption alignright\"><a class=\"shutterset_\" title=\" \" href=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/Protaspis-Olenus-Orsten-coll.-Mantei.jpg\" data-image-id=\"210\" data-src=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/Protaspis-Olenus-Orsten-coll.-Mantei.jpg\" data-thumbnail=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/thumbs\/thumbs_Protaspis-Olenus-Orsten-coll.-Mantei.jpg\" data-title=\"Protaspis-Olenus-Orsten-coll.-Mantei\" data-description=\" \"><img loading=\"lazy\" decoding=\"async\" class=\"ngg-singlepic ngg-right\" title=\"Protaspis-Stadium von Olenus (coll. Mantei, Rostock) in einem oberkambrischen Stinkkalkgeschiebe von Neubrandenburg.\" src=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/thumbs\/thumbs_Protaspis-Olenus-Orsten-coll.-Mantei.jpg\" alt=\"Protaspis-Olenus-Orsten-coll.-Mantei\" width=\"225\" height=\"160\" \/><\/a><figcaption class=\"wp-caption-text\">Protaspis-Stadium von Olenus in einem oberkambrischen Stinkkalkgeschiebe von Neubrandenburg (coll. Mantei, Rostock)<\/figcaption><\/figure>\n<p>Anfang des Jahres wurde der kambrische Stinkkalk (schwed. Orsten) zum Sediment\u00e4rgeschiebe des Jahres 2015 ernannt. Die kambrischen Stinkkalke Schwedens, die im gesamten norddeutschen Vereisungsgebiet zu finden sind (und das nicht mal so selten), stellen ein au\u00dfergew\u00f6hnliches und wenn auch auf den 2. Blick leicht erkennbares Gestein dar. Farblich variieren sie von einem hellen grau bis hin zu tiefschwarz und stechen dadurch eher weniger aus dem Geschiebeinventar heraus. Bei einem ersten Anschlagen mit dem Hammer verstr\u00f6men sie aber einen deutlichen Geruch nach Bitumen, was ihnen auch ihren Namen eingebracht hat. Es soll Sammler geben, die diese Gesteine nur aufschlagen, um sich f\u00fcr ein paar Sekunden an dem Duft zu &#8220;berauschen&#8221;.<\/p>\n<p>Die enthaltenen\u00a0Fossilien, sind spektakul\u00e4r, wenn auch oft ebenfalls erst auf den 2. Blick. Der Orsten z\u00e4hlt zu den sogenannten Konservatfossillagerst\u00e4tten, in ihm hat sich eine reiche Kleinfauna (vorwiegend Arthropoden) aus dem Mittel- und Oberkambrium oft hervorragend erhalten, mitunter sogar in einer detaillierten Weichteilerhaltung.<\/p>\n<p>Johannes Kalbe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anfang des Jahres wurde der kambrische Stinkkalk (schwed. Orsten) zum Sediment\u00e4rgeschiebe des Jahres 2015 ernannt. Die kambrischen Stinkkalke Schwedens, die im gesamten norddeutschen Vereisungsgebiet zu finden sind (und das nicht mal so selten), stellen ein au\u00dfergew\u00f6hnliches und wenn auch auf den 2. Blick leicht erkennbares Gestein dar. Farblich variieren sie von einem hellen grau bis&hellip;&nbsp;<a href=\"https:\/\/www.geschiebekunde.de\/nl\/geschiebe-des-jahres-2015\/\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Gidsgesteenten voor het jaar 2015<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"_bos_mb_destination":[],"footnotes":""},"categories":[8],"tags":[],"class_list":["post-950","post","type-post","status-publish","format-standard","hentry","category-geschiebe-des-jahres"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"nl","enabled_languages":["de","en","nl"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":false,"excerpt":false},"nl":{"title":true,"content":false,"excerpt":false}}},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:11:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/posts\/950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/comments?post=950"}],"version-history":[{"count":9,"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/posts\/950\/revisions"}],"predecessor-version":[{"id":15971,"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/posts\/950\/revisions\/15971"}],"wp:attachment":[{"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/media?parent=950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/categories?post=950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/nl\/wp-json\/wp\/v2\/tags?post=950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}