{"id":834,"date":"2014-03-27T12:46:38","date_gmt":"2014-03-27T11:46:38","guid":{"rendered":"http:\/\/www.geschiebekunde.de\/?p=834"},"modified":"2021-02-06T20:33:11","modified_gmt":"2021-02-06T19:33:11","slug":"geschiebe-des-jahres-2014","status":"publish","type":"post","link":"https:\/\/www.geschiebekunde.de\/en\/geschiebe-des-jahres-2014\/","title":{"rendered":"Boulder of the year 2014"},"content":{"rendered":"<h2 style=\"text-align: justify;\">Die Geschiebe des Jahres 2014<\/h2>\n<p style=\"text-align: justify;\">Die Gesellschaft f\u00fcr Geschiebekunde hat anl\u00e4sslich ihres Neujahrsempfangs im Januar dieses Jahres im Geomatikum der Universit\u00e4t Hamburg das V\u00e4stervik-Fleckengestein und den Beyrichienkalk zu den Geschieben des Jahres 2014 erkl\u00e4rt.<\/p>\n<p style=\"text-align: justify;\">Der Begriff \u201eGeschiebe\u201c gibt dabei schon einen treffenden Hinweis auf die Herkunft dieser Gesteine, stammen sie doch aus skandinavischen Breiten und sind mit den Gletschern der Eiszeiten in die norddeutsche Region \u201egeschoben\u201c worden. Beide Gesteine sind \u00e4u\u00dferst verschieden, aber jedes auf seine Weise sehr interessant.<\/p>\n<p style=\"text-align: justify;\">Das V\u00e4stervik-Fleckengestein ist ein Vertreter der sog. kristallinen Geschiebe und nach der an der Ostseek\u00fcste gelegenen schwedischen Stadt V\u00e4stervik benannt. Seine Grundfarbe ist meist r\u00f6tlich, selten auch grau, und schwarze Flecken verleihen ihm sein attraktives Erscheinungsbild.<\/p>\n<p style=\"text-align: justify;\"><a class=\"shutterset_\" title=\" \" href=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/vaestervik.jpg\" data-image-id=\"208\" data-src=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/vaestervik.jpg\" data-thumbnail=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/thumbs\/thumbs_vaestervik.jpg\" data-title=\"vaestervik\" data-description=\" \"><img loading=\"lazy\" decoding=\"async\" class=\"ngg-singlepic ngg-left alignleft\" src=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/thumbs\/thumbs_vaestervik.jpg\" alt=\"vaestervik\" width=\"255\" height=\"191\" \/><\/a>Die Rekonstruktion seines Ursprungs ist eine spannende Geschichte, die sich ann\u00e4hernd 2 Mrd. Jahre zur\u00fcckverfolgen l\u00e4sst: In einem weitl\u00e4ufigen Flusssystem transportierte Sande und Tone wurden abgelagert und die Sand-Schichtungen weisen auf ein fr\u00fcheres Flussdelta hin, w\u00e4hrend Wellenrippeln und Minerale im Gestein den Einfluss eines nahen Meeres dokumentieren. Als diese Ablagerungen durch Absinken der Erdkruste unter hohe Druck- und Temperaturbedingungen gerieten, sp\u00e4ter dann von den \u00fcberlagernden Schichten durch Erosion befreit wurden, war das heute bei uns vorzufindende Fleckengestein entstanden. Man kann sich kaum der Faszination entziehen, schaut man an der Stra\u00dfe zwischen Gamleby und V\u00e4stervik auf ca. 2000 Millionen Jahre Erdgeschichte und auf die Zeugnisse dieser Geschichte: Wellenrippeln die sich in jener Zeit gebildet haben, so wie wir heute Wellenrippeln an unseren Badestr\u00e4nden sehen.<\/p>\n<p style=\"text-align: justify;\">Allerdings bergen diese Steine auch jetzt noch Geheimnisse in sich, denn in ihnen wurden Minerale gefunden, Zirkone, deren Alter auf mehr als 3 Mrd. Jahre datiert worden sind. Sie deuten darauf hin, dass sich schon eine Mrd. Jahre vor der Bildung des V\u00e4stervik-Fleckengesteins Erdkruste gebildet haben muss, \u00fcber deren Entstehung und Verbleib wir heute zwar viele Annahmen machen k\u00f6nnen, aber \u00fcber die wir noch kaum etwas wirklich wissen.<\/p>\n<p style=\"text-align: justify;\">Nicht so alt wie das V\u00e4stervik-Fleckengestein, im Vergleich dazu sogar recht jung, ist mit etwa 420 Mio. Jahren der aus dem Zeitalter des Silur stammende Beyrichienkalk. Er geh\u00f6rt zur Gruppe der Sediment\u00e4rgeschiebe, ist h\u00e4ufig grau, nimmt aber in verwittertem Zustand einen eher gelblichen Farbton an.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/beyrichienkalk.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"ngg-singlepic ngg-none alignleft\" src=\"http:\/\/www.geschiebekunde.de\/wp-content\/gallery\/geschiebedesjahres\/thumbs\/thumbs_beyrichienkalk.jpg\" alt=\"beyrichienkalk\" width=\"257\" height=\"193\" \/><\/a>Namensgebend f\u00fcr den Beyrichienkalk sind wegen ihres h\u00e4ufigen Auftretens in diesem Gestein die nur Millimeter gro\u00dfen Muschelkrebse Beyrichien. Doch nicht nur Muschelkrebse lassen sich finden. Dieser Kalk ist bei Sammlern gerade wegen seines Fossilreichtums sehr beliebt. Zu den regelm\u00e4\u00dfigen Funden geh\u00f6ren Muscheln, Schnecken, Brachiopoden und Moostierchen &#8211; und mit etwas Gl\u00fcck sind auch Trilobiten- und Fischreste darunter.<\/p>\n<p style=\"text-align: justify;\">Auch ist eine r\u00f6tliche, etwas j\u00fcngere Variante des Beyrichienkalkes bekannt. Von ihr wei\u00df man, dass sie aus Sm\u00e5land in S\u00fcdschweden stammt. F\u00fcr das Herkunftsgebiet der gr\u00e4ulichen Verwandten liegen allerdings bisher nur Vermutungen vor. Diese sind zwar recht fundiert und weisen auf ein \u00f6stlich der schwedischen Insel Gotland gelegenes Gebiet in der Ostsee hin, aber niemand kann seine Hand daf\u00fcr ins Feuer legen, dass nicht die m\u00e4chtigen Eisstr\u00f6me diese Kalke vom skandinavischen Festland vollst\u00e4ndig abgeschliffen und in unsere Regionen verfrachtet haben.<\/p>\n<p style=\"text-align: justify;\">Es wartet somit noch manch eine Frage in der Geschiebeforschung und in den mit ihr verwandten Gebieten auf eine Antwort und viele Funde warten darauf, von Fachleuten, Sammlern und interessierten Laien entdeckt zu werden.<\/p>\n<p style=\"text-align: justify;\">B.Rybicki<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Geschiebe des Jahres 2014 Die Gesellschaft f\u00fcr Geschiebekunde hat anl\u00e4sslich ihres Neujahrsempfangs im Januar dieses Jahres im Geomatikum der Universit\u00e4t Hamburg das V\u00e4stervik-Fleckengestein und den Beyrichienkalk zu den Geschieben des Jahres 2014 erkl\u00e4rt. Der Begriff \u201eGeschiebe\u201c gibt dabei schon einen treffenden Hinweis auf die Herkunft dieser Gesteine, stammen sie doch aus skandinavischen Breiten und&hellip;&nbsp;<a href=\"https:\/\/www.geschiebekunde.de\/en\/geschiebe-des-jahres-2014\/\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Boulder of the year 2014<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"_bos_mb_destination":[],"footnotes":""},"categories":[8],"tags":[],"class_list":["post-834","post","type-post","status-publish","format-standard","hentry","category-geschiebe-des-jahres"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en","nl"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":false,"excerpt":false},"nl":{"title":true,"content":false,"excerpt":false}}},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 20:12:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/posts\/834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/comments?post=834"}],"version-history":[{"count":11,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/posts\/834\/revisions"}],"predecessor-version":[{"id":16494,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/posts\/834\/revisions\/16494"}],"wp:attachment":[{"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/media?parent=834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/categories?post=834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/tags?post=834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}