{"id":713,"date":"2013-05-03T13:00:33","date_gmt":"2013-05-03T12:00:33","guid":{"rendered":"http:\/\/www.geschiebekunde.de\/?p=713"},"modified":"2015-01-19T10:20:20","modified_gmt":"2015-01-19T09:20:20","slug":"das-war-die-29-jahrestagung-der-gesellschaft-fur-geschiebekunde-stralsund","status":"publish","type":"post","link":"https:\/\/www.geschiebekunde.de\/en\/das-war-die-29-jahrestagung-der-gesellschaft-fur-geschiebekunde-stralsund\/","title":{"rendered":"Das war die 29. Jahrestagung der Gesellschaft f\u00fcr Geschiebekunde (Stralsund)"},"content":{"rendered":"<p>Der Auftakt der diesj\u00e4hrigen Jahrestagung erfolgte durch einen Abendvortrag am <strong>Freitag<\/strong> von Herrn\u00a0 Rolf Reinicke \u00fcber das Thema \u201eDie Spuren der Steine\u201c im Forum (Deutsches Meeresmuseum Stralsund).<\/p>\n<p>Am <strong>Samstag<\/strong> folgte ein umfangreiches Vortragsprogramm mit Beitr\u00e4gen von Dirk Pittermann, J\u00f6rg-Florian Jensch, Hildegard Wilske (gehalten von Frank Rudolph), Alfred Buchholz, Werner Beckert, Manfred Kutscher, Frank Rudolph und Reinhard Braasch. Die Themenvielfalt k\u00f6nnte gr\u00f6\u00dfer nicht sein &#8211; vom Kristallin bis zum Sedimentgestein inkl. der beliebten Fossilien war alles dabei. Die Pausen, endlich mal lang genug um etwas ausgiebiger Fachsimpeln zu k\u00f6nnen, erm\u00f6glichten eine kurze Entspannung in der einfach nat\u00fcrlichen und beruhigenden Landschaft des D\u00e4nholm.<\/p>\n<p>Der letzte Tag (<strong>Sonntag<\/strong>) galt den Exkursionen. Vielen Dank an Herrn Kutscher, der es kurzfristig erm\u00f6glichte im Kreideabbau Promoisel nach Fossilien zu suchen.<\/p>\n<p><strong>ngg_shortcode_0_placeholder<\/strong><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p>Ein Dank gilt Herrn <a href=\"&#109;&#x61;i&#108;&#x74;&#111;&#x3a;g&#101;&#x72;h&#x61;&#x72;&#100;&#x2e;s&#99;&#x68;o&#x65;&#x6e;&#101;&#x40;u&#110;&#x73;&#101;&#x72;-&#119;&#x65;d&#101;&#x6c;&#46;&#x64;e\">Gerhard Sch\u00f6ne <\/a> f\u00fcr die Bilder.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Der Auftakt der diesj\u00e4hrigen Jahrestagung erfolgte durch einen Abendvortrag am Freitag von Herrn\u00a0 Rolf Reinicke \u00fcber das Thema \u201eDie Spuren der Steine\u201c im Forum (Deutsches Meeresmuseum Stralsund). Am Samstag folgte ein umfangreiches Vortragsprogramm mit Beitr\u00e4gen von Dirk Pittermann, J\u00f6rg-Florian Jensch, Hildegard Wilske (gehalten von Frank Rudolph), Alfred Buchholz, Werner Beckert, Manfred Kutscher, Frank Rudolph und&hellip;&nbsp;<a href=\"https:\/\/www.geschiebekunde.de\/en\/das-war-die-29-jahrestagung-der-gesellschaft-fur-geschiebekunde-stralsund\/\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Das war die 29. Jahrestagung der Gesellschaft f\u00fcr Geschiebekunde (Stralsund)<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"_bos_mb_destination":[],"footnotes":""},"categories":[7],"tags":[],"class_list":["post-713","post","type-post","status-publish","format-standard","hentry","category-archiv"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en","nl"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"nl":{"title":false,"content":false,"excerpt":false}}},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 04:59:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/posts\/713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/comments?post=713"}],"version-history":[{"count":4,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/posts\/713\/revisions"}],"predecessor-version":[{"id":914,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/posts\/713\/revisions\/914"}],"wp:attachment":[{"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/media?parent=713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/categories?post=713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geschiebekunde.de\/en\/wp-json\/wp\/v2\/tags?post=713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}